{"id":5477,"date":"2021-10-18T09:59:53","date_gmt":"2021-10-18T12:59:53","guid":{"rendered":"https:\/\/coblue.com.br\/blog\/?p=5477"},"modified":"2022-11-08T09:54:10","modified_gmt":"2022-11-08T12:54:10","slug":"avaliacao-de-desempenho","status":"publish","type":"post","link":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/","title":{"rendered":"Avalia\u00e7\u00e3o de Desempenho: o que \u00e9, vantagens e como implementar"},"content":{"rendered":"<p class=\"post-reading-time-estimate__paragraph\">Tempo de leitura: 8 minutos <\/p>\n<p>Afinal, na pr\u00e1tica, o que \u00e9 a <strong>avalia\u00e7\u00e3o de desempenho<\/strong>?<\/p>\n\n\n\n<p>Basicamente, essa \u00e9 uma ferramenta de RH que vai al\u00e9m da an\u00e1lise da performance individual e coletiva dos colaboradores, al\u00e9m de avaliar comportamentos.<\/p>\n\n\n\n<p>Por meio dela \u00e9 poss\u00edvel produzir <a href=\"https:\/\/coblue.com.br\/blog\/feedback\/\">feedbacks<\/a> sobre resultados, avaliar o n\u00edvel de efetividade no trabalho, buscar novos talentos, averiguar a produtividade, e por a\u00ed vai.<\/p>\n\n\n\n<p>S\u00e3o diversos pontos que ir\u00e3o contribuir para a elabora\u00e7\u00e3o de medidas e programas de treinamento para eliminar os problemas identificados, garantindo a expans\u00e3o da organiza\u00e7\u00e3o.<\/p>\n\n\n\n<p>O que n\u00e3o pode ser feito \u00e9 esperar resultados ruins aparecerem. A avalia\u00e7\u00e3o serve como um <strong>acompanhamento cont\u00ednuo, <\/strong>sendo indispens\u00e1vel em todos os n\u00edveis e durante todo o processo da empresa.<\/p>\n\n\n\n<p>Por melhor que seja sua equipe, sempre h\u00e1 poss\u00edveis mudan\u00e7as a serem feitas. A avalia\u00e7\u00e3o de desempenho n\u00e3o \u00e9 uma a\u00e7\u00e3o punitiva, ela pode ser aperfei\u00e7oadora.<\/p>\n\n\n\n<p>Por isso, preparamos um artigo completo sobre tudo o que voc\u00ea precisa saber sobre esse assunto. A seguir, vamos abordar os seguintes t\u00f3picos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"#O-que-\u00e9-avalia\u00e7\u00e3o-de-desempenho?\">O que \u00e9 avalia\u00e7\u00e3o de desempenho?<\/a><\/li><li><a href=\"#Quando-iniciaram-as-avalia\u00e7\u00f5es?\">Quando iniciaram as avalia\u00e7\u00f5es?<\/a><\/li><li><a href=\"#O-que-s\u00e3o-compet\u00eancias-e-resultados?\">O que s\u00e3o compet\u00eancias e resultados?<\/a><\/li><li><a href=\"#Por-que-utilizar-a-avalia\u00e7\u00e3o-de-desempenho?\">Por que utilizar a avalia\u00e7\u00e3o de desempenho?<\/a><\/li><li><a href=\"#Avalia\u00e7\u00e3o-de-desempenho-na-pr\u00e1tica\">Avalia\u00e7\u00e3o de desempenho na pr\u00e1tica<\/a><\/li><li><a href=\"#O-que-\u00e9-gest\u00e3o-de-desempenho?\">O que \u00e9 gest\u00e3o de desempenho?<\/a><\/li><li><a href=\"#Como-a-tecnologia-pode-auxiliar?\">Como a tecnologia pode auxiliar?<\/a><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"O-que-\u00e9-avalia\u00e7\u00e3o-de-desempenho?\"><strong>O que \u00e9 avalia\u00e7\u00e3o de desempenho<\/strong>?<\/h2>\n\n\n\n<p>Esse processo pode ser definido como a avalia\u00e7\u00e3o de um determinado funcion\u00e1rio em um espa\u00e7o de tempo espec\u00edfico. A gest\u00e3o de desempenho \u00e9 um processo que se d\u00e1 em ciclos.<\/p>\n\n\n\n<p>O processo inicia com o estabelecimento de expectativas de desempenho, ou seja, metas, indicadores, compet\u00eancias e comportamentos.<\/p>\n\n\n\n<p>J\u00e1 no t\u00e9rmino, acontece a avalia\u00e7\u00e3o desse desempenho e, logo em seguida, o in\u00edcio de um novo ciclo.\u00a0Ent\u00e3o podemos definir que a avalia\u00e7\u00e3o de desempenho \u00e9 o encerramento do ciclo de gest\u00e3o de desempenho.<\/p>\n\n\n\n<p><strong>Para entender mais sobre o assunto, baixe o nosso eBook gratuito Avalia\u00e7\u00e3o de Desempenho:<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/promo.coblue.com.br\/guia-avaliacao-desempenho\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/Banner-Avaliacao-de-Desempenho.png\" alt=\"banner do ebook sobre avalia\u00e7\u00e3o de desempenho\" class=\"wp-image-6749\" width=\"540\" height=\"305\" srcset=\"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/Banner-Avaliacao-de-Desempenho.png 720w, https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/Banner-Avaliacao-de-Desempenho-300x169.png 300w, https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/Banner-Avaliacao-de-Desempenho-260x146.png 260w, https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/Banner-Avaliacao-de-Desempenho-50x28.png 50w, https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/Banner-Avaliacao-de-Desempenho-133x75.png 133w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Ent\u00e3o, chegamos na parte de mensurar e avaliar o desenvolvimento do colaborador em rela\u00e7\u00e3o \u00e0s expectativas estabelecidas no come\u00e7o do ciclo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Quando-iniciaram-as-avalia\u00e7\u00f5es?\"><strong>Quando iniciaram as avalia\u00e7\u00f5es?<\/strong><\/h2>\n\n\n\n<p>Para entender isso melhor, senta que l\u00e1 vem hist\u00f3ria.<\/p>\n\n\n\n<p>Os comportamentos, que formam uma das duas dimens\u00f5es do desempenho, s\u00e3o avaliados em uma por\u00e7\u00e3o que \u00e9 comumente chamada de \u201cavalia\u00e7\u00e3o por compet\u00eancias\u201d.<\/p>\n\n\n\n<p>O uso de compet\u00eancias e comportamentos na gest\u00e3o de desempenho ganhou for\u00e7a nas d\u00e9cadas de 70 e 80, quando as empresas vinham com enorme uso de metas e objetivos como medida \u00fanica de desempenho.<\/p>\n\n\n\n<p>O uso das metas nasceu com a moda do <em><a href=\"https:\/\/corporatefinanceinstitute.com\/resources\/knowledge\/strategy\/management-by-objectives-mbo\/\">Management by Objectives<\/a><\/em>, ou gest\u00e3o por objetivos.<\/p>\n\n\n\n<p>A quest\u00e3o \u00e9 que, em algum momento, os departamentos de recursos humanos sentiram falta de algo a mais.&nbsp;Faltavam componentes comportamentais que medissem como as pessoas tinham atingido os resultados.<\/p>\n\n\n\n<p>Assim nasceu o uso de compet\u00eancias e comportamentos, que j\u00e1 eram amplamente usados na an\u00e1lise de cargos e ocupa\u00e7\u00f5es, para fins de gest\u00e3o de desempenho.<\/p>\n\n\n\n<p>Agora que entendemos melhor o passado, voltemos ao presente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"O-que-s\u00e3o-compet\u00eancias-e-resultados?\"><strong>O que s\u00e3o compet\u00eancias e resultados<\/strong>?<\/h2>\n\n\n\n<p>Nas avalia\u00e7\u00f5es de desempenho \u201cmodernas\u201d, geralmente h\u00e1 um componente da avalia\u00e7\u00e3o que trata de <strong><em>compet\u00eancias<\/em><\/strong> e outro que trata de <strong><em>resultados<\/em><\/strong>.<\/p>\n\n\n\n<p>Os comportamentos s\u00e3o geralmente avaliados um a um e podem ser agrupados com base em tem\u00e1ticas comuns.<\/p>\n\n\n\n<p>Em algumas empresas, \u00e9 feita uma composi\u00e7\u00e3o entre comportamentos derivados dos valores, das compet\u00eancias cr\u00edticas e das compet\u00eancias funcionais do cargo. Em outras, que optam pela simplicidade, \u00e9 feita apenas a avalia\u00e7\u00e3o das compet\u00eancias cr\u00edticas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Por-que-utilizar-a-avalia\u00e7\u00e3o-de-desempenho?\"><strong>Por que utilizar a avalia\u00e7\u00e3o de desempenho?<\/strong><\/h2>\n\n\n\n<p>Empresas podem passar por dificuldades espec\u00edficas e bem desagrad\u00e1veis ao ignorar a exist\u00eancia de certas ferramentas.<\/p>\n\n\n\n<p>Com toda a certeza, a avalia\u00e7\u00e3o de desempenho \u00e9 uma delas. Caso n\u00e3o haja avalia\u00e7\u00e3o, \u00e9 muito prov\u00e1vel que os funcion\u00e1rios tenham baixa maturidade. Digo a n\u00edvel de liderados e, possivelmente, l\u00edderes.<\/p>\n\n\n\n<p>Como voc\u00ea entende de lideran\u00e7a, sem avaliar o que est\u00e1 ocorrendo com quem o cerca? Como voc\u00ea vai saber se est\u00e1 no caminho correto se n\u00e3o h\u00e1 um \u201cfiltro\u201d em suas a\u00e7\u00f5es?<\/p>\n\n\n\n<p>Se h\u00e1 baixa maturidade dos colaboradores, a empresa tem baixa maturidade tamb\u00e9m.<\/p>\n\n\n\n<p>Pouca mensura\u00e7\u00e3o de resultados, poucas reuni\u00f5es, fraca defini\u00e7\u00e3o de metas, profissionais desalinhados e despreparados. E essa \u00e9 s\u00f3 a ponta do iceberg.<\/p>\n\n\n\n<p>Como saber se todos est\u00e3o no seu devido lugar, se n\u00e3o existe um crit\u00e9rio para colocar ordem?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Avalia\u00e7\u00e3o-de-desempenho-na-pr\u00e1tica\">Avalia\u00e7\u00e3o de desempenho na pr\u00e1tica<\/h2>\n\n\n\n<p>Aqui v\u00e3o alguns passos que s\u00e3o sugest\u00f5es para uma boa fluidez na sua avalia\u00e7\u00e3o.<\/p>\n\n\n\n<p>N\u00e3o h\u00e1 regras ou leis na forma\u00e7\u00e3o das avalia\u00e7\u00f5es, a ideia \u00e9 a cria\u00e7\u00e3o de boas pr\u00e1ticas para identificar, com o tempo, quais as compet\u00eancias que fazem sentido em cada caso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Estabele\u00e7a objetivos para o processo<\/h3>\n\n\n\n<p>Estabelecer os objetivos da avalia\u00e7\u00e3o de desempenho e para quem ela est\u00e1 sendo encaminhada \u00e9 de extrema import\u00e2ncia.<\/p>\n\n\n\n<p>Apesar de termos dito logo acima que n\u00e3o h\u00e1 regras, se eu pudesse criar uma neste exato momento, seria essa. Isso se deve pela singularidade que cada processo deve ter.<\/p>\n\n\n\n<p>Nesse primeiro momento, \u00e9 ideal refletir sobre a cultura da empresa e o que se quer alcan\u00e7ar com o processo.<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 importante entender qual a situa\u00e7\u00e3o das equipes e do colaboradores que passar\u00e3o por essa avalia\u00e7\u00e3o de desempenho.<\/p>\n\n\n\n<p>Lembrando que a avalia\u00e7\u00e3o de desempenho \u00e9 apenas a primeira parte. O ideal \u00e9 o acompanhamento desses m\u00e9todos e resultados, fazendo assim, a gest\u00e3o de desempenho.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Planejar o ciclo<\/h3>\n\n\n\n<p>A equipe deve se organizar para verificar a periodicidade e em quais vias ela se destina.<\/p>\n\n\n\n<p>O ideal \u00e9 que a avalia\u00e7\u00e3o de desempenho seja realizada de forma cont\u00ednua. Assim, se alcan\u00e7a uma melhor an\u00e1lise da evolu\u00e7\u00e3o da empresa como um todo.<\/p>\n\n\n\n<p>Dessa forma, \u00e9 nessa etapa que se cria o percurso dessa avalia\u00e7\u00e3o, ou seja, quais pessoas a ela se destina e como ser\u00e1 esse fluxo.<\/p>\n\n\n\n<p>No caso, pode-se determinar, por exemplo, que a avalia\u00e7\u00e3o s\u00f3 ser\u00e1 feita pelo gestor, ou pelo gestor e o pr\u00f3prio colaborador, e, at\u00e9 mesmo, por estes e outros colaboradores da equipe e clientes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Treinamento para os colaboradores<\/h3>\n\n\n\n<p>N\u00e3o basta saber como fazer avalia\u00e7\u00e3o de desempenho, tem que saber tamb\u00e9m como envolver as equipes no processo. Todo esse processo deve estar muito claro, tanto para gestores, quanto para colaboradores.<\/p>\n\n\n\n<p>Isso facilita que a ades\u00e3o da avalia\u00e7\u00e3o seja significativa e alcance os objetivos do primeiro passo.<\/p>\n\n\n\n<p>Nesse ponto, o RH pode criar reuni\u00f5es com as equipes, e-mails e v\u00eddeos explicativos, e deixar dispon\u00edvel um canal para tirar d\u00favidas e dar sugest\u00f5es de abordagem para gestores e colaboradores.<\/p>\n\n\n\n<p>Uma a\u00e7\u00e3o interessante \u00e9 criar uma demonstra\u00e7\u00e3o da avalia\u00e7\u00e3o de desempenho para que os funcion\u00e1rios fiquem cientes do processo e saibam como agir na hora do preenchimento.<\/p>\n\n\n\n<p>O importante \u00e9 n\u00e3o fazer da avalia\u00e7\u00e3o o \u00fanico passo do processo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"O-que-\u00e9-gest\u00e3o-de-desempenho?\"><strong>O que \u00e9 gest\u00e3o de desempenho?<\/strong><\/h2>\n\n\n\n<p>A avalia\u00e7\u00e3o est\u00e1 ligada diretamente \u00e0 gest\u00e3o, principalmente quando o assunto \u00e9 desempenho.<\/p>\n\n\n\n<p>O resultado s\u00f3 pode ser cobrado ap\u00f3s a lapida\u00e7\u00e3o de uma poss\u00edvel melhora. Voc\u00ea n\u00e3o pode exigir ma\u00e7\u00e3 se sempre plantou banana.<\/p>\n\n\n\n<p>Para isso, outro passo importante \u00e9 gerir os colaboradores com feedbacks, mant\u00ea-los focados na cultura da empresa, cientes de seus deveres, objetivos e ganhos.<\/p>\n\n\n\n<p>Insumos para desenvolvimento, como b\u00f4nus, promo\u00e7\u00f5es e plano de carreira fazem parte um segundo plano nesta fase, mas n\u00e3o deve ser o foco da gest\u00e3o real do colaborador.<\/p>\n\n\n\n<p>Sendo assim, entenda que o in\u00edcio do processo n\u00e3o precisa ser complexo. \u00c0s vezes, algumas quest\u00f5es b\u00e1sicas podem ultrapassar suas expectativas.<\/p>\n\n\n\n<p>Al\u00e9m de demonstrar o interesse da empresa pelo colaborador e seu rendimento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Como-a-tecnologia-pode-auxiliar?\">Como a tecnologia pode auxiliar?<\/h2>\n\n\n\n<p>O Software CoBlue te traz in\u00fameras possibilidades. Dentre elas, algumas est\u00e3o voltadas para a Avalia\u00e7\u00e3o de Desempenho em sua ess\u00eancia, e outras focam mais na Gest\u00e3o de Desempenho.<\/p>\n\n\n\n<p>Neste momento, para seguirmos a l\u00f3gica de conte\u00fado apresentada, falaremos apenas sobre a avalia\u00e7\u00e3o. Por\u00e9m, se ficou curioso, temos duas solu\u00e7\u00f5es.<\/p>\n\n\n\n<p>A primeira \u00e9 aguardar pelo material de Gest\u00e3o de Desempenho, que em breve ser\u00e1 lan\u00e7ado!<\/p>\n\n\n\n<p>E a segunda, <strong>para os mais curiosos, <\/strong>\u00e9 entrar em contato com a CoBlue, temos certeza de que podemos te apresentar uma nova perspectiva sobre avalia\u00e7\u00e3o e gest\u00e3o de desempenho.<\/p>\n\n\n\n<p>Mas voltando ao assunto, o <a href=\"https:\/\/coblue.com.br\/lya\/planos\/\">software CoBlue<\/a> tem como principal diferencial a completa liberdade de parametriza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Como assim? Digamos que ele \u00e9 completamente \u201ccustomiz\u00e1vel\u201d, fazendo com que haja in\u00fameras intera\u00e7\u00f5es e possibilidades dentro do mesmo.<\/p>\n\n\n\n<p>Voc\u00ea precisa saber o que \u00e9 necess\u00e1rio avaliar, de resto, a CoBlue organiza para voc\u00ea.<\/p>\n\n\n\n<p>A avalia\u00e7\u00e3o pode ser feita em 90\u00ba, 180\u00ba ou at\u00e9 mesmo 360\u00ba. As formas de respostas s\u00e3o abrangentes, podendo se restringir a \u201csim ou n\u00e3o\u201d, contadores por nota, por potencial ou at\u00e9 mesmo por agilidade, as possibilidades s\u00e3o gigantescas.<\/p>\n\n\n\n<p>Mesmo sendo feita em 360\u00ba, a avalia\u00e7\u00e3o pode ser feita de forma gradativa e, claro, o software te disponibiliza essas ferramentas.<\/p>\n\n\n\n<p>Provavelmente seria poss\u00edvel fazer um artigo apenas com as possibilidades dentro do software CoBlue, mas como esse n\u00e3o \u00e9 objetivo, lembramos sempre que nossos especialistas est\u00e3o sempre a sua disposi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Voc\u00ea tamb\u00e9m pode gostar destes conte\u00fados:<\/p>\n\n\n\n<p>\ud83d\udc49 <a href=\"https:\/\/coblue.com.br\/blog\/produtividade\/\">Produtividade: como otimizar o desempenho da minha equipe?<\/a><\/p>\n\n\n\n<p>\ud83d\udc49 <a href=\"https:\/\/coblue.com.br\/blog\/fim-de-quarter-avaliacao-enps-e-feedback\/\">Fim de quarter: Avalia\u00e7\u00e3o, eNPS e Feedback<\/a><\/p>\n\n\n<div role=\"main\" id=\"bluenews-conversao-8f7d811f2838a2d7594e\"><\/div>\n<p><script type=\"text\/javascript\" src=\"https:\/\/d335luupugsy2.cloudfront.net\/js\/rdstation-forms\/stable\/rdstation-forms.min.js\"><\/script><script type=\"text\/javascript\"> new RDStationForms('bluenews-conversao-8f7d811f2838a2d7594e', 'UA-53178218-1').createForm();<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo de leitura: 8 minutos Afinal, na pr\u00e1tica, o que \u00e9 a avalia\u00e7\u00e3o de desempenho? Basicamente, essa \u00e9 uma ferramenta de RH que vai al\u00e9m da an\u00e1lise da performance individual e coletiva dos colaboradores, al\u00e9m de avaliar comportamentos. Por meio dela&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[810],"tags":[],"class_list":["post-5477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avaliacao-de-desempenho"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avalia\u00e7\u00e3o de Desempenho: como implementar | Blog CoBlue<\/title>\n<meta name=\"description\" content=\"Todos os detalhes e curiosidades sobre avalia\u00e7\u00e3o de desempenho em um s\u00f3 lugar. O que \u00e9? Como implementar? Quais os benef\u00edcios?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avalia\u00e7\u00e3o de Desempenho: como implementar | Blog CoBlue\" \/>\n<meta property=\"og:description\" content=\"Todos os detalhes e curiosidades sobre avalia\u00e7\u00e3o de desempenho em um s\u00f3 lugar. O que \u00e9? Como implementar? Quais os benef\u00edcios?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog CoBlue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cobluebrasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-18T12:59:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-08T12:54:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2021\/10\/08.10-Avaliacao-de-Desempenho.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"George Eich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Eich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avalia\u00e7\u00e3o de Desempenho: como implementar | Blog CoBlue","description":"Todos os detalhes e curiosidades sobre avalia\u00e7\u00e3o de desempenho em um s\u00f3 lugar. O que \u00e9? Como implementar? Quais os benef\u00edcios?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/","og_locale":"pt_BR","og_type":"article","og_title":"Avalia\u00e7\u00e3o de Desempenho: como implementar | Blog CoBlue","og_description":"Todos os detalhes e curiosidades sobre avalia\u00e7\u00e3o de desempenho em um s\u00f3 lugar. O que \u00e9? Como implementar? Quais os benef\u00edcios?","og_url":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/","og_site_name":"Blog CoBlue","article_publisher":"https:\/\/www.facebook.com\/cobluebrasil","article_published_time":"2021-10-18T12:59:53+00:00","article_modified_time":"2022-11-08T12:54:10+00:00","og_image":[{"width":1152,"height":675,"url":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2021\/10\/08.10-Avaliacao-de-Desempenho.jpg","type":"image\/jpeg"}],"author":"George Eich","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"George Eich","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/#article","isPartOf":{"@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/"},"author":{"name":"George Eich","@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/person\/6638a99b9cd655a0469909ca12e64b50"},"headline":"Avalia\u00e7\u00e3o de Desempenho: o que \u00e9, vantagens e como implementar","datePublished":"2021-10-18T12:59:53+00:00","dateModified":"2022-11-08T12:54:10+00:00","mainEntityOfPage":{"@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/"},"wordCount":1637,"publisher":{"@id":"https:\/\/coblue.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/#primaryimage"},"thumbnailUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2021\/10\/08.10-Avaliacao-de-Desempenho.jpg","articleSection":["Avalia\u00e7\u00e3o de Desempenho"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/","url":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/","name":"Avalia\u00e7\u00e3o de Desempenho: como implementar | Blog CoBlue","isPartOf":{"@id":"https:\/\/coblue.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/#primaryimage"},"image":{"@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/#primaryimage"},"thumbnailUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2021\/10\/08.10-Avaliacao-de-Desempenho.jpg","datePublished":"2021-10-18T12:59:53+00:00","dateModified":"2022-11-08T12:54:10+00:00","description":"Todos os detalhes e curiosidades sobre avalia\u00e7\u00e3o de desempenho em um s\u00f3 lugar. O que \u00e9? Como implementar? Quais os benef\u00edcios?","breadcrumb":{"@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/#primaryimage","url":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2021\/10\/08.10-Avaliacao-de-Desempenho.jpg","contentUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2021\/10\/08.10-Avaliacao-de-Desempenho.jpg","width":1152,"height":675,"caption":"capa do artigo sobre avalia\u00e7\u00e3o de desempenho"},{"@type":"BreadcrumbList","@id":"https:\/\/coblue.com.br\/blog\/avaliacao-de-desempenho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/coblue.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Avalia\u00e7\u00e3o de Desempenho","item":"https:\/\/coblue.com.br\/blog\/category\/avaliacao-de-desempenho\/"},{"@type":"ListItem","position":3,"name":"Avalia\u00e7\u00e3o de Desempenho: o que \u00e9, vantagens e como implementar"}]},{"@type":"WebSite","@id":"https:\/\/coblue.com.br\/blog\/#website","url":"https:\/\/coblue.com.br\/blog\/","name":"Blog CoBlue","description":"Conte\u00fados inspiradores para empresas irresist\u00edveis","publisher":{"@id":"https:\/\/coblue.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coblue.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coblue.com.br\/blog\/#organization","name":"CoBlue","url":"https:\/\/coblue.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/loguinho.png","contentUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/loguinho.png","width":100,"height":100,"caption":"CoBlue"},"image":{"@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cobluebrasil","https:\/\/www.linkedin.com\/company\/coblue\/mycompany\/","https:\/\/br.pinterest.com\/plataformacoblue\/"]},{"@type":"Person","@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/person\/6638a99b9cd655a0469909ca12e64b50","name":"George Eich","sameAs":["http:\/\/coblue.com.br"],"url":"https:\/\/coblue.com.br\/blog\/author\/geiff\/"}]}},"_links":{"self":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts\/5477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5477"}],"version-history":[{"count":27,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts\/5477\/revisions"}],"predecessor-version":[{"id":8658,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts\/5477\/revisions\/8658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/media\/5778"}],"wp:attachment":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}