{"id":7229,"date":"2022-05-03T10:32:59","date_gmt":"2022-05-03T13:32:59","guid":{"rendered":"https:\/\/coblue.com.br\/blog\/?p=7229"},"modified":"2022-12-16T12:31:08","modified_gmt":"2022-12-16T15:31:08","slug":"6-dicas-para-ter-colaboradores-engajados","status":"publish","type":"post","link":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/","title":{"rendered":"6 dicas para manter colaboradores engajados"},"content":{"rendered":"<p class=\"post-reading-time-estimate__paragraph\">Tempo de leitura: 6 minutos <\/p>\n<p>Se voc\u00ea est\u00e1 aqui procurando dicas de como manter seus colaboradores engajados, \u00e9 porque j\u00e1 entendeu a import\u00e2ncia que isso tem nos locais de trabalho, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p>Atualmente, \u00e9 poss\u00edvel dizer que essa \u00e9 uma das principais chaves para o sucesso do neg\u00f3cio. <\/p>\n\n\n\n<p>Isso porque o <a href=\"https:\/\/coblue.com.br\/blog\/poder-do-engajamento\/\"><strong>engajamento<\/strong><\/a> dos colaboradores est\u00e1 diretamente ligado \u00e0 sua <strong><a href=\"https:\/\/coblue.com.br\/blog\/produtividade-10-dicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">produtividade<\/a><\/strong> que, consequentemente, resulta em uma \u00f3tima receita.<\/p>\n\n\n\n<p>Qualquer estrat\u00e9gia dentro de um neg\u00f3cio s\u00f3 vai funcionar se as equipes se empenharem de verdade e se sentirem conectadas \u00e0 empresa.<\/p>\n\n\n\n<p>Mas essa realidade ainda \u00e9 um grande desafio para muitas organiza\u00e7\u00f5es.<\/p>\n\n\n\n<p>De acordo com uma pesquisa feita pela <a href=\"https:\/\/arquivos.progic.com.br\/blogs\/Progic-Comunicacao-Interna-Trends-2022.pdf\"><strong>Progic<\/strong><\/a>, ter colaboradores desengajados \u00e9 um dos maiores problemas atuais das empresas e sustentar o engajamento est\u00e1 sendo o maior desafio de 2022.<\/p>\n\n\n\n<p>Mas ent\u00e3o como fazer para engajar minha equipe?<\/p>\n\n\n\n<p>Confira abaixo 6 dicas que separamos para te ajudar nessa miss\u00e3o:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">1. Tenha uma gest\u00e3o participativa<\/h4>\n\n\n\n<p>Uma <a href=\"https:\/\/hbr.org\/2016\/11\/how-the-best-ceos-differ-from-average-ones\"><strong>pesquisa de Harvard<\/strong><\/a> mostrou que saber escutar todas as pessoas que est\u00e3o dentro da empresa \u00e9 um dos pontos mais importantes para ser um \u00f3timo l\u00edder.<\/p>\n\n\n\n<p>E essa \u00e9 uma a\u00e7\u00e3o fundamental para tornar sua<strong> gest\u00e3o mais participativa<\/strong>. Afinal, ouvir o colaborador \u00e9 um dos primeiros passos para estreitar la\u00e7os e, assim, pensar em a\u00e7\u00f5es que realmente estejam condizentes com a realidade da equipe.<\/p>\n\n\n\n<p>Essa proximidade \u00e9 capaz de trazer muitos benef\u00edcios, como por exemplo, elevar senso de pertencimento e valoriza\u00e7\u00e3o do profissional. <\/p>\n\n\n\n<p>Al\u00e9m disso, ter uma gest\u00e3o mais participativa \u00e9 essencial para fortalecer a <a href=\"https:\/\/coblue.com.br\/blog\/cultura-organizacional\/\"><strong>cultura organizacional<\/strong><\/a> e criar maior confian\u00e7a entre todos da equipe no ambiente de trabalho (fatores que t\u00eam impacto direto sobre o engajamento do time).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">2. Mantenha uma rotina de feedbacks<\/h4>\n\n\n\n<p>O <a href=\"https:\/\/coblue.com.br\/blog\/feedback\/\"><strong>feedback<\/strong><\/a> \u00e9 mais do que fundamental quando estamos falando da gest\u00e3o de pessoas.<\/p>\n\n\n\n<p>Afinal, \u00e9 atrav\u00e9s de feedbacks cont\u00ednuos que os colaboradores e a empresa como um todo conseguem entender quais s\u00e3o os pontos fortes e quais precisam ser melhorados. <\/p>\n\n\n\n<p>Isso promove mais alinhamento entre os objetivos e as responsabilidades de todas as partes envolvidas, e tamb\u00e9m permite combater um grande inimigo do engajamento, que \u00e9 a falta de reconhecimento.<\/p>\n\n\n\n<p>De acordo com a <a href=\"https:\/\/radios.ebc.com.br\/tarde-nacional-amazonia\/2019\/06\/brasil-e-o-segundo-pais-com-maior-indice-de-estresse-relacionado-ao\"><strong>ISMA-BR<\/strong><\/a> (International Stress Management Association), esse fator est\u00e1 relacionado \u00e0 89% dos casos de insatisfa\u00e7\u00e3o dos brasileiros com seu trabalho.<\/p>\n\n\n\n<p>Ou seja, isso mostra que a falta de reconhecimento est\u00e1 diretamente relacionada ao desengajamento e pode fazer com que as pessoas saiam em busca de novas oportunidades em outras empresas.<\/p>\n\n\n\n<p>Portanto, \u00e9 necess\u00e1rio combat\u00ea-la. <\/p>\n\n\n\n<p>Mas lembre-se: para serem efetivos, os feedbacks precisam ser relevantes e seguidos de um plano de a\u00e7\u00e3o para trazer novos resultados.<\/p>\n\n\n\n<p>Afinal, n\u00e3o \u00e9 poss\u00edvel continuar fazendo as mesmas coisas e torcer para que aconte\u00e7a algo diferente.<\/p>\n\n\n\n<p>No nosso <a href=\"https:\/\/promo.coblue.com.br\/manual-feedback-2022\"><strong>e-book gratuito: Manual Pr\u00e1tico do Feedback<\/strong><\/a> voc\u00ea tem acesso a muita informa\u00e7\u00e3o e dicas sobre o assunto.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">3. &nbsp;Incentive o autodesenvolvimento<\/h4>\n\n\n\n<p>Pessoas que sentem que est\u00e3o sendo incentivadas a se desenvolverem pessoalmente e profissionalmente tendem a permanecer mais engajadas.<\/p>\n\n\n\n<p>Por isso, oferecer oportunidades de desenvolvimento aos colaboradores \u00e9 uma \u00f3tima a\u00e7\u00e3o.<\/p>\n\n\n\n<p>O investimento em cursos e treinamentos externos \u00e9 um bom exemplo disso, mas nem sempre \u00e9 algo vi\u00e1vel. Ent\u00e3o, outra possibilidade \u00e9 adotar treinamentos e trocas internas entre profissionais ou entre um time e outro.<\/p>\n\n\n\n<p>Essa troca ajuda os colaboradores a \u201cpensarem fora da caixa\u201d e buscarem a resolu\u00e7\u00e3o de problemas sob uma nova perspectiva, por exemplo.<\/p>\n\n\n\n<p>Uma \u00f3tima forma de visualizar quais pessoas precisam ser desenvolvidas \u00e9 utilizar a matriz <a href=\"https:\/\/coblue.com.br\/blog\/9box-na-pratica\/\"><strong>9box<\/strong><\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4. Promova a sa\u00fade mental<\/h4>\n\n\n\n<p>Cada dia mais estamos escutando e falando sobre a sa\u00fade mental dos colaboradores, n\u00e3o \u00e9 mesmo? Hoje j\u00e1 sabemos que a produtividade deles est\u00e1 diretamente conectada com o seu bem-estar.<\/p>\n\n\n\n<p>Estudos feitos pela <a href=\"https:\/\/warwick.ac.uk\/\"><strong>Universidade de Warwick<\/strong><\/a>, a felicidade eleva em 12% a produtividade, j\u00e1 colaboradores infelizes s\u00e3o 10% menos produtivos.<\/p>\n\n\n\n<p>Por muito tempo l\u00edderes e gestores consideravam somente a vida profissional para mensurar isto, mas principalmente nos \u00faltimos tempos, vimos que n\u00e3o \u00e9 bem assim. A vida pessoal tamb\u00e9m tem uma grande influ\u00eancia nisso.<\/p>\n\n\n\n<p>Por isso, \u00e9 importante ter um <a href=\"https:\/\/promo.coblue.com.br\/ebook-termometro\"><strong>term\u00f4metro emocional<\/strong><\/a> para obter dados efetivos sobre como anda o humor das pessoas e manter avalia\u00e7\u00f5es de <a href=\"https:\/\/promo.coblue.com.br\/box-okr-bemestar\"><strong>bem-estar<\/strong><\/a> para mensurar como est\u00e3o todas as esferas da vida dos seus colaboradores.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">5. Ofere\u00e7a oportunidades de crescimento dentro da empresa<\/h4>\n\n\n\n<p>Voc\u00ea sabia que um a cada quatro colaboradores n\u00e3o v\u00eaem espa\u00e7o para se desenvolver com sucesso dentro da empresa em que trabalham? \u00c9 isso que a pesquisa feita pela <a href=\"https:\/\/www.tinypulse.com\/2014-employee-engagement-organizational-culture-report#section-iii\"><strong>Tiny Pulse<\/strong><\/a> mostrou.<\/p>\n\n\n\n<p>Assim como o autodesenvolvimento, ter oportunidades de crescimento profissional dentro da empresa \u00e9 imprescind\u00edvel.<\/p>\n\n\n\n<p>Quando voc\u00ea estipula e alinha as expectativas com suas equipes, a visualiza\u00e7\u00e3o do que precisa ser feito para alcan\u00e7ar os seus objetivos profissionais ficam muito mais claros.<\/p>\n\n\n\n<p>Nesse sentido, adotar o uso do <a href=\"https:\/\/coblue.com.br\/blog\/pdi-e-okr\/\"><strong>PDI e OKR<\/strong><\/a> \u00e9 um \u00f3timo caminho para gest\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">6. Desenvolva lideran\u00e7as inspiradoras<\/h4>\n\n\n\n<p>Colaboradores engajados exigem <a href=\"https:\/\/coblue.com.br\/blog\/dicas-de-lideranca\/\"><strong>lideran\u00e7as<\/strong><\/a> mais humanas, estrat\u00e9gicas e inspiradoras.<\/p>\n\n\n\n<p>Quando a lideran\u00e7a \u00e9 capaz de inspirar, ela promove melhorias muito mais significativas na vida e no trabalho das pessoas.<\/p>\n\n\n\n<p>N\u00e3o por acaso, segundo a<strong> <\/strong><a href=\"https:\/\/www.gallup.com\/workplace\/231593\/why-great-managers-rare.aspx\"><strong>Gallup<\/strong><\/a>, os l\u00edderes respondem por 70% da varia\u00e7\u00e3o no engajamento das equipes, determinando o sucesso dos seus resultados.<\/p>\n\n\n\n<p>Al\u00e9m disso, <a href=\"https:\/\/www.fastcompany.com\/3068771\/how-employees-at-apple-and-google-are-more-productive\"><strong>estudos <\/strong><\/a>revelam que um colaborador que se sente inspirado no trabalho \u00e9 quase 125% mais produtivo do que um que est\u00e1 apenas satisfeito.<\/p>\n\n\n\n<p>Por isso, as lideran\u00e7as que mais inspiram seu time s\u00e3o as que possuem melhor desempenho.<\/p>\n\n\n\n<p>A tend\u00eancia para 2022, de acordo com a <a href=\"https:\/\/arquivos.progic.com.br\/blogs\/Progic-Comunicacao-Interna-Trends-2022.pdf\"><strong>Progic<\/strong><\/a>, \u00e9 que as empresas foquem mais no desenvolvimento da comunica\u00e7\u00e3o das lideran\u00e7as, al\u00e9m na melhora das a\u00e7\u00f5es de comunica\u00e7\u00e3o internas.<\/p>\n\n\n\n<p>Isso porque s\u00e3o as lideran\u00e7as que s\u00e3o respons\u00e1veis por passar a cultura da empresa para o seu time, al\u00e9m de fazer a gest\u00e3o constante do desenvolvimento e bem-estar das pessoas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">DICA EXTRA: Tenha as ferramentas certas para medir o engajamento dos seus colaboradores<\/h4>\n\n\n\n<p>Lembre-se sempre que engajamento n\u00e3o pode ser uma quest\u00e3o de percep\u00e7\u00e3o.<\/p>\n\n\n\n<p>Como quase tudo nos neg\u00f3cios, <strong>\u00e9 necess\u00e1rio mensurar esse aspecto com dados concretos para conseguir agir sobre ele com efici\u00eancia. <\/strong><\/p>\n\n\n\n<p>Por isso, tenha as ferramentas certas para medir o engajamento e torar seu processo decis\u00f3rio mais assertivo e estrat\u00e9gico.<\/p>\n\n\n\n<p>Atrav\u00e9s do nosso <strong><a href=\"https:\/\/coblue.com.br\/lya\/plano_desempenho\/\">Plano Desempenho<\/a><\/strong>, voc\u00ea tem as ferramentas ideais para mensurar e assim otimizar muitos dos aspectos que trouxemos aqui.<\/p>\n\n\n\n<p>Fale conosco e entenda como podemos te auxiliar a engajar seu time e fazer com que ele tenha mais desempenho!<\/p>\n\n\n\n<p>Por hoje \u00e9 s\u00f3, esperamos que voc\u00ea tenha gostado do conte\u00fado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Para ficar por dentro das nossas novidades e conferir em primeira m\u00e3o os materiais incr\u00edveis que n\u00f3s produzimos, assine a nossa newsletter! \ud83d\udc47\ud83c\udffb<\/p>\n\n\n<div role=\"main\" id=\"bluenews-conversao-8f7d811f2838a2d7594e\"><\/div>\n<p><script type=\"text\/javascript\" src=\"https:\/\/d335luupugsy2.cloudfront.net\/js\/rdstation-forms\/stable\/rdstation-forms.min.js\"><\/script><script type=\"text\/javascript\"> new RDStationForms('bluenews-conversao-8f7d811f2838a2d7594e', 'UA-53178218-1').createForm();<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo de leitura: 6 minutos Se voc\u00ea est\u00e1 aqui procurando dicas de como manter seus colaboradores engajados, \u00e9 porque j\u00e1 entendeu a import\u00e2ncia que isso tem nos locais de trabalho, n\u00e3o \u00e9 mesmo? Atualmente, \u00e9 poss\u00edvel dizer que essa \u00e9 uma&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[820],"tags":[],"class_list":["post-7229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engajamento-e-retencao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6 dicas para ter colaboradores engajados | Blog CoBlue<\/title>\n<meta name=\"description\" content=\"Neste artigo trouxemos 6 dicas para te ajudar a engajar e elevar a produtividade de cada membro da sua equipe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 dicas para ter colaboradores engajados | Blog CoBlue\" \/>\n<meta property=\"og:description\" content=\"Neste artigo trouxemos 6 dicas para te ajudar a engajar e elevar a produtividade de cada membro da sua equipe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog CoBlue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cobluebrasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T13:32:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-16T15:31:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/05\/Dicas-engajamento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"George Eich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Eich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 dicas para ter colaboradores engajados | Blog CoBlue","description":"Neste artigo trouxemos 6 dicas para te ajudar a engajar e elevar a produtividade de cada membro da sua equipe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/","og_locale":"pt_BR","og_type":"article","og_title":"6 dicas para ter colaboradores engajados | Blog CoBlue","og_description":"Neste artigo trouxemos 6 dicas para te ajudar a engajar e elevar a produtividade de cada membro da sua equipe.","og_url":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/","og_site_name":"Blog CoBlue","article_publisher":"https:\/\/www.facebook.com\/cobluebrasil","article_published_time":"2022-05-03T13:32:59+00:00","article_modified_time":"2022-12-16T15:31:08+00:00","og_image":[{"width":1152,"height":675,"url":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/05\/Dicas-engajamento.jpg","type":"image\/jpeg"}],"author":"George Eich","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"George Eich","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/#article","isPartOf":{"@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/"},"author":{"name":"George Eich","@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/person\/6638a99b9cd655a0469909ca12e64b50"},"headline":"6 dicas para manter colaboradores engajados","datePublished":"2022-05-03T13:32:59+00:00","dateModified":"2022-12-16T15:31:08+00:00","mainEntityOfPage":{"@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/"},"wordCount":1132,"publisher":{"@id":"https:\/\/coblue.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/#primaryimage"},"thumbnailUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/05\/Dicas-engajamento.jpg","articleSection":["Engajamento e Reten\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/","url":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/","name":"6 dicas para ter colaboradores engajados | Blog CoBlue","isPartOf":{"@id":"https:\/\/coblue.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/#primaryimage"},"image":{"@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/#primaryimage"},"thumbnailUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/05\/Dicas-engajamento.jpg","datePublished":"2022-05-03T13:32:59+00:00","dateModified":"2022-12-16T15:31:08+00:00","description":"Neste artigo trouxemos 6 dicas para te ajudar a engajar e elevar a produtividade de cada membro da sua equipe.","breadcrumb":{"@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/#primaryimage","url":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/05\/Dicas-engajamento.jpg","contentUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/05\/Dicas-engajamento.jpg","width":1152,"height":675,"caption":"capa do artigo sobrer dicas para engajar"},{"@type":"BreadcrumbList","@id":"https:\/\/coblue.com.br\/blog\/6-dicas-para-ter-colaboradores-engajados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/coblue.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Engajamento e Reten\u00e7\u00e3o","item":"https:\/\/coblue.com.br\/blog\/category\/engajamento-e-retencao\/"},{"@type":"ListItem","position":3,"name":"6 dicas para manter colaboradores engajados"}]},{"@type":"WebSite","@id":"https:\/\/coblue.com.br\/blog\/#website","url":"https:\/\/coblue.com.br\/blog\/","name":"Blog CoBlue","description":"Conte\u00fados inspiradores para empresas irresist\u00edveis","publisher":{"@id":"https:\/\/coblue.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coblue.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coblue.com.br\/blog\/#organization","name":"CoBlue","url":"https:\/\/coblue.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/loguinho.png","contentUrl":"https:\/\/coblue.com.br\/blog\/wp-content\/uploads\/2022\/02\/loguinho.png","width":100,"height":100,"caption":"CoBlue"},"image":{"@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cobluebrasil","https:\/\/www.linkedin.com\/company\/coblue\/mycompany\/","https:\/\/br.pinterest.com\/plataformacoblue\/"]},{"@type":"Person","@id":"https:\/\/coblue.com.br\/blog\/#\/schema\/person\/6638a99b9cd655a0469909ca12e64b50","name":"George Eich","sameAs":["http:\/\/coblue.com.br"],"url":"https:\/\/coblue.com.br\/blog\/author\/geiff\/"}]}},"_links":{"self":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts\/7229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7229"}],"version-history":[{"count":25,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts\/7229\/revisions"}],"predecessor-version":[{"id":9688,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/posts\/7229\/revisions\/9688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/media\/7230"}],"wp:attachment":[{"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coblue.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}